{"id":1008,"count":0,"description":"","link":"https:\/\/avtoprevleke.si\/it\/kategorije-izdelkov\/avtoprevleke-po-meri\/toyota\/yaris\/","name":"Yaris","slug":"yaris","taxonomy":"product_cat","parent":961,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yaris Archives - Avtoprevleke po meri | TECH PLUS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avtoprevleke.si\/it\/categorie-di-prodotto\/coprisedili-per-auto-personalizzati\/toyota\/yaris\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yaris Archives - Avtoprevleke po meri | TECH PLUS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avtoprevleke.si\/it\/categorie-di-prodotto\/coprisedili-per-auto-personalizzati\/toyota\/yaris\/\" \/>\n<meta property=\"og:site_name\" content=\"Avtoprevleke po meri | TECH PLUS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/kategorije-izdelkov\\\/avtoprevleke-po-meri\\\/toyota\\\/yaris\\\/\",\"url\":\"https:\\\/\\\/avtoprevleke.si\\\/kategorije-izdelkov\\\/avtoprevleke-po-meri\\\/toyota\\\/yaris\\\/\",\"name\":\"Yaris Archives - Avtoprevleke po meri | TECH PLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/kategorije-izdelkov\\\/avtoprevleke-po-meri\\\/toyota\\\/yaris\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/kategorije-izdelkov\\\/avtoprevleke-po-meri\\\/toyota\\\/yaris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/avtoprevleke.si\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avtoprevleke po meri\",\"item\":\"https:\\\/\\\/avtoprevleke.si\\\/kategorije-izdelkov\\\/avtoprevleke-po-meri\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toyota\",\"item\":\"https:\\\/\\\/avtoprevleke.si\\\/kategorije-izdelkov\\\/avtoprevleke-po-meri\\\/toyota\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Yaris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/#website\",\"url\":\"https:\\\/\\\/avtoprevleke.si\\\/\",\"name\":\"Avtoprevleke po meri | TECH PLUS\",\"description\":\"Tipske avtoprevleke - sede\u017ene prevleke za avto\",\"publisher\":{\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avtoprevleke.si\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/#organization\",\"name\":\"Avtoprevleke po meri | TECH PLUS\",\"url\":\"https:\\\/\\\/avtoprevleke.si\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avtoprevleke.si\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/avtoprevleke-logo.png\",\"contentUrl\":\"https:\\\/\\\/avtoprevleke.si\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/avtoprevleke-logo.png\",\"width\":856,\"height\":330,\"caption\":\"Avtoprevleke po meri | TECH PLUS\"},\"image\":{\"@id\":\"https:\\\/\\\/avtoprevleke.si\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yaris Archives - Avtoprevleke po meri | TECH PLUS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avtoprevleke.si\/it\/categorie-di-prodotto\/coprisedili-per-auto-personalizzati\/toyota\/yaris\/","og_locale":"it_IT","og_type":"article","og_title":"Yaris Archives - Avtoprevleke po meri | TECH PLUS","og_url":"https:\/\/avtoprevleke.si\/it\/categorie-di-prodotto\/coprisedili-per-auto-personalizzati\/toyota\/yaris\/","og_site_name":"Avtoprevleke po meri | TECH PLUS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/avtoprevleke.si\/kategorije-izdelkov\/avtoprevleke-po-meri\/toyota\/yaris\/","url":"https:\/\/avtoprevleke.si\/kategorije-izdelkov\/avtoprevleke-po-meri\/toyota\/yaris\/","name":"Yaris Archives - Avtoprevleke po meri | TECH PLUS","isPartOf":{"@id":"https:\/\/avtoprevleke.si\/#website"},"breadcrumb":{"@id":"https:\/\/avtoprevleke.si\/kategorije-izdelkov\/avtoprevleke-po-meri\/toyota\/yaris\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/avtoprevleke.si\/kategorije-izdelkov\/avtoprevleke-po-meri\/toyota\/yaris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/avtoprevleke.si\/"},{"@type":"ListItem","position":2,"name":"Avtoprevleke po meri","item":"https:\/\/avtoprevleke.si\/kategorije-izdelkov\/avtoprevleke-po-meri\/"},{"@type":"ListItem","position":3,"name":"Toyota","item":"https:\/\/avtoprevleke.si\/kategorije-izdelkov\/avtoprevleke-po-meri\/toyota\/"},{"@type":"ListItem","position":4,"name":"Yaris"}]},{"@type":"WebSite","@id":"https:\/\/avtoprevleke.si\/#website","url":"https:\/\/avtoprevleke.si\/","name":"Coprisedili personalizzati per auto | TECH PLUS","description":"Teli copriauto standard - coprisedili per auto","publisher":{"@id":"https:\/\/avtoprevleke.si\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avtoprevleke.si\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/avtoprevleke.si\/#organization","name":"Coprisedili personalizzati per auto | TECH PLUS","url":"https:\/\/avtoprevleke.si\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/avtoprevleke.si\/#\/schema\/logo\/image\/","url":"https:\/\/avtoprevleke.si\/wp-content\/uploads\/2018\/09\/avtoprevleke-logo.png","contentUrl":"https:\/\/avtoprevleke.si\/wp-content\/uploads\/2018\/09\/avtoprevleke-logo.png","width":856,"height":330,"caption":"Avtoprevleke po meri | TECH PLUS"},"image":{"@id":"https:\/\/avtoprevleke.si\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avtoprevleke.si\/it\/wp-json\/wp\/v2\/product_cat\/1008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avtoprevleke.si\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/avtoprevleke.si\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/avtoprevleke.si\/it\/wp-json\/wp\/v2\/product_cat\/961"}],"wp:post_type":[{"href":"https:\/\/avtoprevleke.si\/it\/wp-json\/wp\/v2\/product?product_cat=1008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}